{"id":110,"count":1,"description":"","link":"https:\/\/www.dimel.com.br\/blog\/tag\/alicate-de-pressao-no-ipiranga\/","name":"alicate de press\u00e3o no Ipiranga","slug":"alicate-de-pressao-no-ipiranga","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivo de alicate de press\u00e3o no Ipiranga - Blog Dimel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dimel.com.br\/blog\/tag\/alicate-de-pressao-no-ipiranga\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de alicate de press\u00e3o no Ipiranga - Blog Dimel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dimel.com.br\/blog\/tag\/alicate-de-pressao-no-ipiranga\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Dimel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.dimel.com.br\/blog\/tag\/alicate-de-pressao-no-ipiranga\/\",\"url\":\"https:\/\/www.dimel.com.br\/blog\/tag\/alicate-de-pressao-no-ipiranga\/\",\"name\":\"Arquivo de alicate de press\u00e3o no Ipiranga - Blog Dimel\",\"isPartOf\":{\"@id\":\"https:\/\/www.dimel.com.br\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.dimel.com.br\/blog\/tag\/alicate-de-pressao-no-ipiranga\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dimel.com.br\/blog\/tag\/alicate-de-pressao-no-ipiranga\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.dimel.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"alicate de press\u00e3o no Ipiranga\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dimel.com.br\/blog\/#website\",\"url\":\"https:\/\/www.dimel.com.br\/blog\/\",\"name\":\"Blog Dimel\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.dimel.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dimel.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.dimel.com.br\/blog\/#organization\",\"name\":\"Blog Dimel\",\"url\":\"https:\/\/www.dimel.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.dimel.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.dimel.com.br\/blog\/wp-content\/uploads\/2025\/02\/logo-3.png\",\"contentUrl\":\"https:\/\/www.dimel.com.br\/blog\/wp-content\/uploads\/2025\/02\/logo-3.png\",\"width\":500,\"height\":250,\"caption\":\"Blog Dimel\"},\"image\":{\"@id\":\"https:\/\/www.dimel.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de alicate de press\u00e3o no Ipiranga - Blog Dimel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dimel.com.br\/blog\/tag\/alicate-de-pressao-no-ipiranga\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivo de alicate de press\u00e3o no Ipiranga - Blog Dimel","og_url":"https:\/\/www.dimel.com.br\/blog\/tag\/alicate-de-pressao-no-ipiranga\/","og_site_name":"Blog Dimel","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.dimel.com.br\/blog\/tag\/alicate-de-pressao-no-ipiranga\/","url":"https:\/\/www.dimel.com.br\/blog\/tag\/alicate-de-pressao-no-ipiranga\/","name":"Arquivo de alicate de press\u00e3o no Ipiranga - Blog Dimel","isPartOf":{"@id":"https:\/\/www.dimel.com.br\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.dimel.com.br\/blog\/tag\/alicate-de-pressao-no-ipiranga\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.dimel.com.br\/blog\/tag\/alicate-de-pressao-no-ipiranga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.dimel.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"alicate de press\u00e3o no Ipiranga"}]},{"@type":"WebSite","@id":"https:\/\/www.dimel.com.br\/blog\/#website","url":"https:\/\/www.dimel.com.br\/blog\/","name":"Blog Dimel","description":"","publisher":{"@id":"https:\/\/www.dimel.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dimel.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.dimel.com.br\/blog\/#organization","name":"Blog Dimel","url":"https:\/\/www.dimel.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.dimel.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.dimel.com.br\/blog\/wp-content\/uploads\/2025\/02\/logo-3.png","contentUrl":"https:\/\/www.dimel.com.br\/blog\/wp-content\/uploads\/2025\/02\/logo-3.png","width":500,"height":250,"caption":"Blog Dimel"},"image":{"@id":"https:\/\/www.dimel.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.dimel.com.br\/blog\/wp-json\/wp\/v2\/tags\/110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dimel.com.br\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.dimel.com.br\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.dimel.com.br\/blog\/wp-json\/wp\/v2\/posts?tags=110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}